{"id":24,"date":"2016-07-05T14:49:02","date_gmt":"2016-07-05T14:49:02","guid":{"rendered":"http:\/\/flatsome.dev\/?page_id=8220"},"modified":"2024-05-09T07:14:19","modified_gmt":"2024-05-09T07:14:19","slug":"grid-style-3","status":"publish","type":"page","link":"https:\/\/wpsolutionbd.com\/ecommerce2\/demos\/shop-demos\/grid-style-3\/","title":{"rendered":"Grid Style 3"},"content":{"rendered":"\t<section class=\"section has-parallax\" id=\"section_787916111\">\n\t\t<div class=\"bg section-bg fill bg-fill  \" data-parallax-container=\".section\" data-parallax-background data-parallax=\"-3\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 0px 1px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n  <div class=\"banner-grid-wrapper\">\n  <div id=\"banner-grid-1343292144\" class=\"banner-grid row row-grid row-small\" data-packery-options=\"\">\n                      \n<div class=\"col grid-col small-12 large-6 grid-col-1\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-1307262607\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1294273495\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text \">\n              \n              <div class=\"text-inner text-left\">\n                  \n<p class=\"lead alt-font\"><span style=\"font-size: 190%;\">Add any text here&#8230;<\/span><\/p>\n<h2 class=\"uppercase\"><span style=\"font-size: 130%;\"><strong>New arrivals on the shop<\/strong><\/span><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n<a class=\"button primary is-outline is-larger\"  >\n    <span>Browse<\/span>\n  <\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1294273495 {\n  width: 50%;\n}\n#text-box-1294273495 .text {\n  font-size: 99%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1307262607 {\n  padding-top: 500px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1307262607 .bg.bg-loaded {\n  background-image: url(https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\n}\n#banner-1307262607 .bg {\n  background-position: 65% 16%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col small-7 large-3 grid-col-1\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-224951326\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1771987903\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Add Any Headline here<\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1771987903 {\n  width: 60%;\n}\n#text-box-1771987903 .text {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1771987903 {\n    width: 76%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-224951326 {\n  padding-top: 500px;\n}\n#banner-224951326 .bg.bg-loaded {\n  background-image: url(https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-2-300x195.jpg);\n}\n#banner-224951326 .bg {\n  background-position: 58% 24%;\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col small-5 large-3 grid-col-1-2\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-1616466669\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-579568267\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Add Any Headline here<\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-579568267 {\n  width: 60%;\n}\n#text-box-579568267 .text {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-579568267 {\n    width: 67%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1616466669 {\n  padding-top: 500px;\n}\n#banner-1616466669 .bg.bg-loaded {\n  background-image: url(https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-2-300x195.jpg);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n<div class=\"col grid-col small-5 large-3 grid-col-1-2\" ><div class=\"col-inner box-shadow-1\">\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-1560136151\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-836440143\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>Add Any Headline here<\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-836440143 {\n  width: 60%;\n}\n#text-box-836440143 .text {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-836440143 {\n    width: 68%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1560136151 {\n  padding-top: 500px;\n}\n#banner-1560136151 .bg.bg-loaded {\n  background-image: url(https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-2-300x195.jpg);\n}\n<\/style>\n  <\/div>\n\n\n<\/div><\/div>\n            <\/div>\n    <style>\n    #banner-grid-1343292144 .grid-col-1{height: 600px}\n    #banner-grid-1343292144 .grid-col-1-2{height: 300px}\n    #banner-grid-1343292144 .grid-col-1-3{height:200px}\n    #banner-grid-1343292144 .grid-col-2-3{height: 400px}\n    #banner-grid-1343292144 .grid-col-1-4{height: 150px}\n    #banner-grid-1343292144 .grid-col-3-4{height: 450px}\n\n\n    \n    \n\n  <\/style>\n    <\/div>\n  \n\t\t<\/div>\n\n\t\t\n<style>\n#section_787916111 {\n  padding-top: 19px;\n  padding-bottom: 19px;\n  background-color: rgb(246, 246, 246);\n}\n#section_787916111 .section-bg.bg-loaded {\n  background-image: url(https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"container section-title-container\" style=\"margin-top:22px;\"><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">Featured Products<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  \t<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">Featured Categories<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n          <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Baby Lotion\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/baby-lotion\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/41nsfyt743l-sl1001-webb-300x300.jpg\" alt=\"Baby Lotion\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Baby Lotion                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      4 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n                <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Face Primer\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/face-primer\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/71-wgyytzxl-ac-sl1500-web-300x300.jpg\" alt=\"Face Primer\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Face Primer                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      6 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n                <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Hair Care\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/hair-care\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/9fc05940-04f3-11ed-b4c0-55491f1bbb6d-web-300x300.jpg\" alt=\"Hair Care\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Hair Care                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      4 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n                <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Hair straightener\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/hair-straightener\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/123-blush-5-1-300x300.jpg\" alt=\"Hair straightener\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Hair straightener                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      4 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n                <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Khadi Natural\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/khadi-natural\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/03-activated-bamboo-charcoal-front-back-1-300x300.jpg\" alt=\"Khadi Natural\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Khadi Natural                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      4 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n                <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Mehedi\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/mehedi\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/prem-dulhan-mehedi-01-300x300.jpg\" alt=\"Mehedi\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Mehedi                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      4 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n                <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Personal Care\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/personal-care\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/sheglam-primer-1-300x300.jpg\" alt=\"Personal Care\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Personal Care                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      4 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n                <div class=\"product-category col\" >\n            <div class=\"col-inner\">\n              <a aria-label=\"Visit product category Skin Care\" href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/product-category\/skin-care\/\">                <div class=\"box box-category has-hover box-badge hover-dark \">\n                <div class=\"box-image\" >\n                  <div class=\"\" >\n                  <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2024\/05\/technic-pore-perfect-primer-4-800x800-1-300x300.jpg\" alt=\"Skin Care\" width=\"300\" height=\"300\" \/>                                                      <\/div>\n                <\/div>\n                <div class=\"box-text text-center\" >\n                  <div class=\"box-text-inner\">\n                      <h5 class=\"uppercase header-title\">\n                              Skin Care                      <\/h5>\n                                            <p class=\"is-xsmall uppercase count \">\n\t                      4 Products                      <\/p>\n                                            \n                  <\/div>\n                <\/div>\n                <\/div>\n            <\/a>            <\/div>\n            <\/div>\n        <\/div>\n\t<div id=\"gap-764958674\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-764958674 {\n  padding-top: 36px;\n}\n<\/style>\n\t<\/div>\n\t\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-1400023036\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-1\" data-parallax-container=\".banner\" data-parallax-background>\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2096119873\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>Signup for Newsletter<\/strong><\/h3>\n<p class=\"lead\">Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonumm.<\/p>\n\t<div id=\"gap-238817485\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-238817485 {\n  padding-top: 18px;\n}\n<\/style>\n\t<\/div>\n\t\n<p>(insert contact form here)<\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2096119873 {\n  width: 78%;\n}\n#text-box-2096119873 .text {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-2096119873 {\n    width: 37%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1400023036 {\n  padding-top: 366px;\n}\n#banner-1400023036 .bg.bg-loaded {\n  background-image: url(https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-2.jpg);\n}\n#banner-1400023036 .overlay {\n  background-color: rgba(0, 0, 0, 0.26);\n}\n#banner-1400023036 .bg {\n  background-position: 60% 0%;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">Latest news<\/span><b><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}'>\n\n  \t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/hello-world\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Hello world!<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">April 27, 2024<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Welcome to WordPress. This is your first post. Edit or delete it, then start writing! [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                                            <p class=\"from_the_blog_comments uppercase is-xsmall\">\n                            1 Comment                        <\/p>\n                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/welcome-to-flatsome\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Welcome to Flatsome<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Welcome to WordPress. This is your first post. Edit or delete it, then start blogging! [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">19<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Nov<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/velkommen-til-bloggen-min\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Just another post with A Gallery<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetur adipiscing elit. In sed vulputate massa. Fusce ante magna, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Oct<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/a-simple-blog-post\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">A Simple Blog Post<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">13<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Oct<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item has-post-icon\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/a-video-blog-post\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t\t\t<div class=\"absolute no-click x50 y50 md-x50 md-y50 lg-x50 lg-y50\">\n  \t\t\t\t            \t<div class=\"overlay-icon\">\n  \t\t\t\t                    <i class=\"icon-play\"><\/i>\n  \t\t\t\t                <\/div>\n  \t\t\t\t            <\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">A Video Blog Post<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetur adipiscing elit. In sed vulputate massa. Fusce ante magna, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">01<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Jan<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/just-a-cool-blog-post-with-images\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Just a cool blog post with Images<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetur adipiscing elit. In sed vulputate massa. Fusce ante magna, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">30<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Dec<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/just-a-cool-blog-post-with-a-gallery-2\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Another post with A Gallery<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetur adipiscing elit. In sed vulputate massa. Fusce ante magna, [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">16<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Dec<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/wpsolutionbd.com\/ecommerce2\/new-client-landed\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:200px;\">\n  \t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"195\" src=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1-300x195.jpg 300w, https:\/\/wpsolutionbd.com\/ecommerce2\/wp-content\/uploads\/2016\/08\/dummy-1.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">New Client Landed<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt \">Lorem ipsum dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"badge absolute top post-date badge-square\">\n\t\t\t\t\t\t\t<div class=\"badge-inner\">\n\t\t\t\t\t\t\t\t<span class=\"post-date-day\">29<\/span><br>\n\t\t\t\t\t\t\t\t<span class=\"post-date-month is-xsmall\">Aug<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-bold-center\"><b><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\"><i class=\"icon-instagram\" ><\/i>Follow on instagram<\/span><b><\/b><\/h3><\/div>\nInstagram did not return a 200.\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":6,"parent":64,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-24","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/pages\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":1,"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/pages\/24\/revisions"}],"predecessor-version":[{"id":99,"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/pages\/24\/revisions\/99"}],"up":[{"embeddable":true,"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/pages\/64"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/media\/6"}],"wp:attachment":[{"href":"https:\/\/wpsolutionbd.com\/ecommerce2\/wp-json\/wp\/v2\/media?parent=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}